{"id":1755,"date":"2023-10-30T11:31:39","date_gmt":"2023-10-30T10:31:39","guid":{"rendered":"https:\/\/www.oddoboni.it\/portfolio\/biagiotti-vvff-ancona-copy-copy\/"},"modified":"2024-01-29T12:14:55","modified_gmt":"2024-01-29T11:14:55","slug":"idealmarmi-italia","status":"publish","type":"portfolio","link":"https:\/\/www.oddoboni.it\/en\/portfolio\/idealmarmi-italia\/","title":{"rendered":"Idealmarmi Italia"},"content":{"rendered":"<p>[vc_section][vc_row][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]<strong>Customer<\/strong>: Idealmarmi Italia[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]<strong>Category<\/strong>: Marble and Stone for Building[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;cli-cat&#8221;][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_row][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;1756,1758,1763,1761,1762,1759,1760&#8243; img_size=&#8221;full&#8221; onclick=&#8221;img_link_large&#8221; css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;popup-gallery&#8221;][\/vc_column][\/vc_row][vc_section][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h5>Richiedi maggiori informazioni<\/h5>\n<p>[\/vc_column_text][vc_raw_html]JTVCY29udGFjdC1mb3JtLTclMjBpZCUzRCUyMjU0JTIyJTIwdGl0bGUlM0QlMjJSaWNoaWVkaSUyMFByZXZlbnRpdm8lMjIlNUQ=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_section][vc_row][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]Customer: Idealmarmi Italia[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]Category: Marble and Stone for Building[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;cli-cat&#8221;][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_row][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;1756,1758,1763,1761,1762,1759,1760&#8243; img_size=&#8221;full&#8221; onclick=&#8221;img_link_large&#8221; css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;popup-gallery&#8221;][\/vc_column][\/vc_row][vc_section][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Richiedi maggiori informazioni [\/vc_column_text][vc_raw_html]JTVCY29udGFjdC1mb3JtLTclMjBpZCUzRCUyMjU0JTIyJTIwdGl0bGUlM0QlMjJSaWNoaWVkaSUyMFByZXZlbnRpdm8lMjIlNUQ=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"author":2,"featured_media":1762,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"portfolio_category":[6,10],"portfolio_tag":[26],"class_list":["post-1755","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-arredamento","portfolio_category-edilizia","portfolio_tag-metalmeccanica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Idealmarmi Italia - Oddo Boni<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Idealmarmi Italia - Oddo Boni\" \/>\n<meta property=\"og:description\" content=\"[vc_section][vc_row][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]Customer: Idealmarmi Italia[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]Category: Marble and Stone for Building[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;cli-cat&#8221;][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_row][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;1756,1758,1763,1761,1762,1759,1760&#8243; img_size=&#8221;full&#8221; onclick=&#8221;img_link_large&#8221; css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;popup-gallery&#8221;][\/vc_column][\/vc_row][vc_section][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Richiedi maggiori informazioni [\/vc_column_text][vc_raw_html]JTVCY29udGFjdC1mb3JtLTclMjBpZCUzRCUyMjU0JTIyJTIwdGl0bGUlM0QlMjJSaWNoaWVkaSUyMFByZXZlbnRpdm8lMjIlNUQ=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][\/vc_section]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Oddo Boni\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T11:14:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oddoboni.it\/wp-content\/uploads\/2023\/10\/Idealmarmi-Tavolo-01-30x40-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1474\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oddoboni.it\/#website\",\"url\":\"https:\/\/www.oddoboni.it\/\",\"name\":\"Oddo Boni\",\"description\":\"image - communication\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oddoboni.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.oddoboni.it\/wp-content\/uploads\/2023\/10\/Idealmarmi-Tavolo-01-30x40-1.jpg\",\"contentUrl\":\"https:\/\/www.oddoboni.it\/wp-content\/uploads\/2023\/10\/Idealmarmi-Tavolo-01-30x40-1.jpg\",\"width\":1474,\"height\":2000},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#webpage\",\"url\":\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/\",\"name\":\"Idealmarmi Italia - Oddo Boni\",\"isPartOf\":{\"@id\":\"https:\/\/www.oddoboni.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#primaryimage\"},\"datePublished\":\"2023-10-30T10:31:39+00:00\",\"dateModified\":\"2024-01-29T11:14:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oddoboni.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/www.oddoboni.it\/portfolio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Idealmarmi Italia\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Idealmarmi Italia - Oddo Boni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/","og_locale":"en_US","og_type":"article","og_title":"Idealmarmi Italia - Oddo Boni","og_description":"[vc_section][vc_row][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]Customer: Idealmarmi Italia[\/vc_column_text][\/vc_column][vc_column width=&#8221;2\/6&#8243;][vc_column_text el_class=&#8221;cli-cat&#8221;]Category: Marble and Stone for Building[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;cli-cat&#8221;][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_row][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;1756,1758,1763,1761,1762,1759,1760&#8243; img_size=&#8221;full&#8221; onclick=&#8221;img_link_large&#8221; css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;popup-gallery&#8221;][\/vc_column][\/vc_row][vc_section][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Richiedi maggiori informazioni [\/vc_column_text][vc_raw_html]JTVCY29udGFjdC1mb3JtLTclMjBpZCUzRCUyMjU0JTIyJTIwdGl0bGUlM0QlMjJSaWNoaWVkaSUyMFByZXZlbnRpdm8lMjIlNUQ=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][\/vc_section]","og_url":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/","og_site_name":"Oddo Boni","article_modified_time":"2024-01-29T11:14:55+00:00","og_image":[{"width":1474,"height":2000,"url":"https:\/\/www.oddoboni.it\/wp-content\/uploads\/2023\/10\/Idealmarmi-Tavolo-01-30x40-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.oddoboni.it\/#website","url":"https:\/\/www.oddoboni.it\/","name":"Oddo Boni","description":"image - communication","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oddoboni.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.oddoboni.it\/wp-content\/uploads\/2023\/10\/Idealmarmi-Tavolo-01-30x40-1.jpg","contentUrl":"https:\/\/www.oddoboni.it\/wp-content\/uploads\/2023\/10\/Idealmarmi-Tavolo-01-30x40-1.jpg","width":1474,"height":2000},{"@type":"WebPage","@id":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#webpage","url":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/","name":"Idealmarmi Italia - Oddo Boni","isPartOf":{"@id":"https:\/\/www.oddoboni.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#primaryimage"},"datePublished":"2023-10-30T10:31:39+00:00","dateModified":"2024-01-29T11:14:55+00:00","breadcrumb":{"@id":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.oddoboni.it\/portfolio\/idealmarmi-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oddoboni.it\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.oddoboni.it\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Idealmarmi Italia"}]}]}},"_links":{"self":[{"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/portfolio\/1755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/comments?post=1755"}],"version-history":[{"count":2,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/portfolio\/1755\/revisions"}],"predecessor-version":[{"id":1971,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/portfolio\/1755\/revisions\/1971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/media\/1762"}],"wp:attachment":[{"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/media?parent=1755"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/portfolio_category?post=1755"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/www.oddoboni.it\/en\/wp-json\/wp\/v2\/portfolio_tag?post=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}